{"id":2361,"date":"2015-02-15T21:28:15","date_gmt":"2015-02-15T20:28:15","guid":{"rendered":"http:\/\/wordpress.judo-steinheim.de\/?p=2361"},"modified":"2020-02-12T21:29:29","modified_gmt":"2020-02-12T20:29:29","slug":"rehn-und-kramer-erkaempfen-fahrkarte-fuer-die-nationalen-titelkaempfe","status":"publish","type":"post","link":"https:\/\/www.judo-steinheim.de\/index.php\/2015\/02\/15\/rehn-und-kramer-erkaempfen-fahrkarte-fuer-die-nationalen-titelkaempfe\/","title":{"rendered":"Rehn und Kramer erk\u00e4mpfen Fahrkarte f\u00fcr die nationalen Titelk\u00e4mpfe"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"667\" src=\"http:\/\/wordpress.judo-steinheim.de\/wp-content\/uploads\/2020\/02\/15_02_15_Pforzheim_01.jpg\" alt=\"\" class=\"wp-image-2362\" srcset=\"https:\/\/www.judo-steinheim.de\/wp-content\/uploads\/2020\/02\/15_02_15_Pforzheim_01.jpg 500w, https:\/\/www.judo-steinheim.de\/wp-content\/uploads\/2020\/02\/15_02_15_Pforzheim_01-225x300.jpg 225w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bei den S\u00fcddeutschen Einzelmeisterschaften der unter Einundzwanzigj\u00e4hrigen erk\u00e4mpfen sich Lena-Sophie Rehn (bis 70\u00a0kg) und Guido Kramer (bis 90\u00a0kg) vom JudoTeam Steinheim in Pforzheim die Bronzemedaillen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Lena-Sophie Rehn konnte wegen eines Infektes leider die\nLandesmeisterschaften in ihrer eigentlichen Altersklasse, Jugend unter achtzehn\nJahren, nicht bestreiten und ein Start bei den Gruppenmeisterschaften blieb ihr\nverwehrt. Bei den Junioren war f\u00fcr diese Titelk\u00e4mpfe noch ein Startplatz frei,\nallerdings eine Klasse h\u00f6her bis 70&nbsp;Kilogramm. Ein Versuch war es wert und\nRehn nutzte das Angebot, denn es gab nichts zu verlieren. Unbefangen und frech\nging die Sechzehnj\u00e4hrige in ihre K\u00e4mpfe. Gegen Rebecca Lex aus Kronwinkel kam\nsie mit einem Uchi-Mata (Innenschenkelh\u00fcftwurf) mit anschlie\u00dfendem Haltegriff\nzum Erfolg. Eine Niederlage durch Haltegriff musste sie gegen Bayerin Tatjana\nSchauer einstecken. In der Trostrunde setzte sie sich gegen Alina Kretschmer\naus Bruchsal mit einer Gro\u00dfen Innensichel durch. Bronzenes Edelmetall und das\ndamit verbundene Ticket nach Frankfurt\/Oder erk\u00e4mpfte sie sich mit zwei\nUchi-Mata-W\u00fcrfen gegen Hannah Kitzberger vom TSV Grafing. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guido Kramer startet mit zwei schnellen Siegen in die Meisterschaft. Der Steinheimer kam dabei mit Uchi-Mata gegen den Ingolst\u00e4dter Matthias Werner und Daniel Bengel aus Schw\u00e4bisch Gm\u00fcnd mit einem Schulterwurf zum Erfolg. Im Halbfinale traf er auf Bayerns Nummer eins, Tim G\u00fcther vom TSV M\u00fcnchen-Gro\u00dfhadern. Nach gutem Standkampf unterlag der Steinheimer durch einen Haltegriff. Die Bronzemedaille sicherte sich Kramer mit einem fulminanten O-Soto-Gari (Gro\u00dfe Au\u00dfensichel) gegen den Bayerischen Meister Simon H\u00f6llrich aus M\u00fcnchen bereits nach drei Sekunden. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"889\" src=\"http:\/\/wordpress.judo-steinheim.de\/wp-content\/uploads\/2020\/02\/15_02_15_Pforzheim_02.jpg\" alt=\"\" class=\"wp-image-2363\" srcset=\"https:\/\/www.judo-steinheim.de\/wp-content\/uploads\/2020\/02\/15_02_15_Pforzheim_02.jpg 500w, https:\/\/www.judo-steinheim.de\/wp-content\/uploads\/2020\/02\/15_02_15_Pforzheim_02-169x300.jpg 169w\" sizes=\"auto, (max-width: 500px) 85vw, 500px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Felix Huber (bis 60&nbsp;kg) und Juliane Walter (bis\n63&nbsp;kg) verpassten nach guten K\u00e4mpfen mit f\u00fcnften Pl\u00e4tzen knapp das Podest.\nJan K\u00f6nig (bis 81&nbsp;kg) wurde Siebter. Bei den Deutschen Meisterschaften\nwerden noch Catrin Schopper (bis 57&nbsp;kg) und Rebecca Br\u00e4uniger (bis\n63&nbsp;kg) f\u00fcr das JudoTeam Steinheim an den Start gehen. Beide sind als\nBundeskaderathletinnen auf diese Meisterschaften bereits gesetzt. Jana\nScheffold kann sich f\u00fcr diese Meisterschaften noch \u00fcber die nationalen\nTitelk\u00e4mpfe der Jugend qualifizieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei den S\u00fcddeutschen Einzelmeisterschaften der unter Einundzwanzigj\u00e4hrigen erk\u00e4mpfen sich Lena-Sophie Rehn (bis 70\u00a0kg) und Guido Kramer (bis 90\u00a0kg) vom JudoTeam Steinheim in Pforzheim die Bronzemedaillen.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2361","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=2361"}],"version-history":[{"count":1,"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2361\/revisions"}],"predecessor-version":[{"id":2364,"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/posts\/2361\/revisions\/2364"}],"wp:attachment":[{"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=2361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=2361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.judo-steinheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=2361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}